{"id":33120,"date":"2020-05-31T16:41:19","date_gmt":"2020-05-31T14:41:19","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/sonia-garcia-navasquillo\/"},"modified":"2025-10-14T23:23:54","modified_gmt":"2025-10-14T21:23:54","slug":"sonia-garcia-navasquillo","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/pt-pt\/network\/sonia-garcia-navasquillo\/","title":{"rendered":"Sonia Garc\u00eca Navasquillo"},"content":{"rendered":"<p>Sonia Garcia Navasquillo \u00e9 advogada espanhola (admitida na Ordem dos Advogados da Espanha &#8211; Val\u00eancia) e advogada especializada em negocia\u00e7\u00f5es, contratos, governan\u00e7a corporativa e gest\u00e3o de lit\u00edgios a n\u00edvel internacional. Possui grande experi\u00eancia em projetos internacionais, principalmente no setor de energia. Formado em \u00e1reas relacionadas com Direito Empresarial Internacional (LL.M), compliance, resolu\u00e7\u00e3o de lit\u00edgios e contrata\u00e7\u00e3o internacional.<\/p>\n<p>Sonia Garc\u00eda, s\u00f3cia fundadora da Garcia Legal, tem assessorado em quest\u00f5es societ\u00e1rias e projetos de investimento estrangeiro, joint ventures, gest\u00e3o de opera\u00e7\u00f5es de exporta\u00e7\u00e3o e cria\u00e7\u00e3o de canais de distribui\u00e7\u00e3o como ag\u00eancias, franquias e outros representantes. Trabalhou como advogada interna para v\u00e1rias multinacionais e como advogada de apoio profissional para escrit\u00f3rios internacionais, como o The Brauw Blackstone Westbroek, onde esteve envolvida em processos de due diligence, arbitragem comercial\/ ADR internacional e lit\u00edgios. Presta assessoria em situa\u00e7\u00f5es complexas de contratos internacionais e est\u00e1 regularmente envolvida na e-discovery em grandes casos jur\u00eddicos relacionados com corrup\u00e7\u00e3o e crimes financeiros.<\/p>\n<p>Ela tamb\u00e9m foi palestrante convidado na Leiden Law School (International Contract Law) e na The Hague University of Applied Sciences (&#8216;Aspectos pr\u00e1ticos da devida dilig\u00eancia em negocia\u00e7\u00f5es de contratos&#8217;) 2019-2020 no \u00e2mbito do Projeto Comenius patrocinado pelo Minist\u00e9rio da Educa\u00e7\u00e3o dos Pa\u00edses Baixos.<\/p>\n<p>Sonia obteve o seu LL. M em Direito Empresarial Internacional na Universidade Erasmus (Roterd\u00e3o). Obteve o diploma da C\u00e2mara de Com\u00e9rcio Internacional em Advanced ICC PIDA (arbitragem) e um diploma em Rela\u00e7\u00f5es Internacionais\/ Negocia\u00e7\u00e3o Internacional no Instituto Clingendael em Haia e em Supply Chain Management (RSM, Rotterdam). \u00c9 autora de v\u00e1rias publica\u00e7\u00f5es sobre diferen\u00e7as culturais e o impacto nos neg\u00f3cios e participou como membro do painel em v\u00e1rios semin\u00e1rios sobre fazer neg\u00f3cios na Am\u00e9rica Latina.<\/p>\n<p>Ela \u00e9 fluente em espanhol, ingl\u00eas, italiano, holand\u00eas e franc\u00eas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sonia Garcia Navasquillo \u00e9 advogada espanhola (admitida na Ordem dos Advogados da Espanha &#8211; Val\u00eancia) e advogada especializada em negocia\u00e7\u00f5es, contratos, governan\u00e7a corporativa e gest\u00e3o de lit\u00edgios a n\u00edvel internacional. Possui grande experi\u00eancia em projetos internacionais, principalmente no setor de energia. Formado em \u00e1reas relacionadas com Direito Empresarial Internacional (LL.M), compliance, resolu\u00e7\u00e3o de lit\u00edgios e [&hellip;]<\/p>\n","protected":false},"author":626,"featured_media":16328,"template":"","sector":[12623],"country":[12289,11624],"skill":[12533,12506,12509,12492],"class_list":["post-33120","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-en-pt-pt","country-the-hague-pt-pt","country-nl-pt-pt","skill-international-trade-pt-pt","skill-compliance-pt-pt","skill-corporate-pt-pt","skill-alternative-dispute-resolution-pt-pt"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/vendor\/33120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/users\/626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/media\/16328"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=33120"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/sector?post=33120"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/country?post=33120"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/skill?post=33120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}