{"id":32123,"date":"2025-04-24T10:18:54","date_gmt":"2025-04-24T08:18:54","guid":{"rendered":"https:\/\/www.legalmondo.com\/?post_type=vendor&#038;p=32123"},"modified":"2025-04-24T10:18:54","modified_gmt":"2025-04-24T08:18:54","slug":"christopher-miller","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/pt-pt\/network\/christopher-miller\/","title":{"rendered":"Christopher Miller"},"content":{"rendered":"<p>Christopher A. Miller \u00e9 associado da Miller Shah LLP no seu escrit\u00f3rio de Filad\u00e9lfia.<\/p>\n<p>Christopher concentra a sua pr\u00e1tica em lit\u00edgios comerciais complexos, incluindo den\u00fancias, valores mobili\u00e1rios, benef\u00edcios para empregados e lit\u00edgios de prote\u00e7\u00e3o do consumidor. Tamb\u00e9m representa empresas americanas e internacionais em v\u00e1rios aspectos das suas necessidades transaccionais, incluindo a elabora\u00e7\u00e3o e negocia\u00e7\u00e3o de contratos, governa\u00e7\u00e3o empresarial e fus\u00f5es e aquisi\u00e7\u00f5es.<\/p>\n<p>O Christopher est\u00e1 autorizado a exercer na Commonwealth da Pensilv\u00e2nia e no Tribunal Distrital dos Estados Unidos para o Distrito Oriental da Pensilv\u00e2nia. Para al\u00e9m destas jurisdi\u00e7\u00f5es, tem trabalhado em casos com advogados locais e co-conselheiros em todos os Estados Unidos. Christopher \u00e9 membro da American Bar Association e da Pennsylvania Bar Association.<\/p>\n<p>Christopher obteve a sua licenciatura em Direito na Faculdade de Direito da Universidade de Michigan e o seu bacharelato na Universidade de Cornell. Antes de se tornar advogado, Christopher foi professor de ingl\u00eas e treinador de debates numa grande universidade na cidade de Ho Chi Minh, no Vietname. Christopher tamb\u00e9m trabalhou anteriormente para a C\u00e2mara dos Comuns do Reino Unido e para um escrit\u00f3rio de advogados em Parma, It\u00e1lia.<\/p>\n<p>Christopher fala ingl\u00eas e domina o italiano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christopher A. Miller \u00e9 associado da Miller Shah LLP no seu escrit\u00f3rio de Filad\u00e9lfia. Christopher concentra a sua pr\u00e1tica em lit\u00edgios comerciais complexos, incluindo den\u00fancias, valores mobili\u00e1rios, benef\u00edcios para empregados e lit\u00edgios de prote\u00e7\u00e3o do consumidor. Tamb\u00e9m representa empresas americanas e internacionais em v\u00e1rios aspectos das suas necessidades transaccionais, incluindo a elabora\u00e7\u00e3o e negocia\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":768,"featured_media":32139,"template":"","sector":[],"country":[11645,12328,12785],"skill":[12537,12508,12509,12535],"class_list":["post-32123","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","country-us-pt-pt","country-philadelphia-pt-pt","country-us-pa-pt-pt","skill-litigation-pt-pt","skill-contracts-pt-pt","skill-corporate-pt-pt","skill-labor-pt-pt"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/vendor\/32123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/users\/768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/media\/32139"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=32123"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/sector?post=32123"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/country?post=32123"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/pt-pt\/wp-json\/wp\/v2\/skill?post=32123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}