{"id":6260,"date":"2018-03-12T22:36:01","date_gmt":"2018-03-12T21:36:01","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/stefano-dindo\/"},"modified":"2021-10-26T16:07:52","modified_gmt":"2021-10-26T14:07:52","slug":"stefano-dindo","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/it\/network\/stefano-dindo\/","title":{"rendered":"Stefano Dindo"},"content":{"rendered":"<p>Stefano Dindo \u00e8 un avvocato italiano specializzato in diritto commerciale, societario, bancario, fallimentare, internazionale, successorio e arbitrale, vitivinicolo e alimentare.<\/p>\n<p>Si \u00e8 laureato in Giurisprudenza presso l\u2019Universit\u00e0 di Bologna con il massimo dei voti. \u00c8 iscritto all\u2019Albo degli Avvocati di Verona dal 1977 ed \u00e8 uno dei partner dello studio Dindo, Zorzi e associati.<\/p>\n<p>Stefano \u00e8 membro del Consiglio di Presidenza dell\u2019UIA (Union Internationale des Avocats, Paris) e Presidente del relativo gruppo di lavoro di diritto alimentare; \u00e8 Presidente Nazionale dell\u2019UGIVI (Unione Giuristi della Vite e del Vino); \u00e8 Vice Presidente Onorario dell\u2019AIJA (Associazione Internazionale Giovani Avvocati) ed \u00e8 stato rappresentante onorario per il Veneto dell\u2019American Chamber of Commerce in Italia.<\/p>\n<p>\u00c8 autore di articoli giuridici e relatore in numerosi seminari riguardanti le sue aree di specializzazione.<\/p>\n<p>Stefano \u00e8 di madrelingua italiana e parla correntemente inglese e francese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stefano Dindo \u00e8 un avvocato italiano specializzato in diritto commerciale, societario, bancario, fallimentare, internazionale, successorio e arbitrale, vitivinicolo e alimentare.<\/p>\n","protected":false},"author":383,"featured_media":34055,"template":"","sector":[195],"country":[154,159],"skill":[164,332,304,171],"class_list":["post-6260","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-it","country-it-it","country-verona-it","skill-commercio-internazionale","skill-diritto-agrario","skill-diritto-alimentare","skill-real-estate-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor\/6260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/users\/383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media\/34055"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media?parent=6260"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/sector?post=6260"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/country?post=6260"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/skill?post=6260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}