{"id":29821,"date":"2024-07-24T19:49:10","date_gmt":"2024-07-24T17:49:10","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/thomas-kriense\/"},"modified":"2024-07-24T19:52:11","modified_gmt":"2024-07-24T17:52:11","slug":"thomas-kriense","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/it\/network\/thomas-kriense\/","title":{"rendered":"Thomas Kriense"},"content":{"rendered":"<p>Thomas esercita la professione di avvocato dal 2012. Dopo essersi laureato all&#8217;Universit\u00e0 di Leiden, ha acquisito esperienza presso boutique di propriet\u00e0 intellettuale e studi legali di medie dimensioni. Ha lavorato a lungo per la Fondazione BREIN (&#8220;Stichting BREIN&#8221;), un&#8217;organizzazione dedicata alla protezione dei diritti d&#8217;autore nel mercato digitale. Oggi gestisce uno studio di consulenza e contenzioso e si occupa principalmente di propriet\u00e0 intellettuale, informatica, media e privacy.<\/p>\n<p>Thomas \u00e8 specializzato in questioni complesse di propriet\u00e0 intellettuale, nella redazione di contratti (IT) e nella collaborazione con i clienti per lo sviluppo di strategie di protezione della propriet\u00e0 intellettuale, di valorizzazione dei dati e di protezione dei dati. In una societ\u00e0 in cui la privacy sta diventando sempre pi\u00f9 importante a causa della digitalizzazione e dei big data, Thomas si concentra anche sulla conformit\u00e0 in questo settore.<\/p>\n<p>Thomas parla correntemente inglese e olandese e ha una conoscenza di base del tedesco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thomas esercita la professione di avvocato dal 2012. Dopo essersi laureato all&#8217;Universit\u00e0 di Leiden, ha acquisito esperienza presso boutique di propriet\u00e0 intellettuale e studi legali di medie dimensioni. Ha lavorato a lungo per la Fondazione BREIN (&#8220;Stichting BREIN&#8221;), un&#8217;organizzazione dedicata alla protezione dei diritti d&#8217;autore nel mercato digitale. Oggi gestisce uno studio di consulenza e [&hellip;]<\/p>\n","protected":false},"author":749,"featured_media":34416,"template":"","sector":[195],"country":[169,163],"skill":[114,2245,3047,149,3131],"class_list":["post-29821","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-it","country-amsterdam-it","country-nl-it","skill-contenzioso","skill-media-it","skill-privacy-and-data-security-it","skill-proprieta-intellettuale","skill-information-technology-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor\/29821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/users\/749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media\/34416"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media?parent=29821"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/sector?post=29821"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/country?post=29821"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/skill?post=29821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}