{"id":28399,"date":"2023-12-16T00:13:42","date_gmt":"2023-12-15T23:13:42","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/jean-louis-collart\/"},"modified":"2023-12-16T00:18:25","modified_gmt":"2023-12-15T23:18:25","slug":"jean-louis-collart","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/it\/network\/jean-louis-collart\/","title":{"rendered":"Jean-Louis Collart"},"content":{"rendered":"\n<p>Jean-Louis Collart vanta una solida formazione giuridica e una lunga esperienza nella consulenza ai clienti in materia commerciale e civile, nonch\u00e9 in materia di contenzioso, diritto delle successioni e protezione dei dati.<\/p>\n\n\n\n<p>\u00c8 stato ammesso all&#8217;albo degli avvocati di Ginevra nel 1988. Una volta superato l&#8217;esame di abilitazione, \u00e8 entrato a far parte di un noto studio legale di Zurigo. Ha poi trascorso 3 anni presso l&#8217;ufficio legale di UBS Ginevra prima di tornare all&#8217;avvocatura.<\/p>\n\n\n\n<p>Recentemente (2021) ha fondato lo studio legale boutique ginevrino <a href=\"https:\/\/www.athenalaw.ch\/\" data-type=\"link\" data-id=\"https:\/\/www.athenalaw.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">ATHENA<\/a>, dove esercita.<\/p>\n\n\n\n<p>Impegnato in diverse organizzazioni di diritto internazionale, pu\u00f2 avvalersi di un&#8217;ampia rete internazionale per fornire consulenza a clienti locali e internazionali.<\/p>\n\n\n\n<p>Avendo fatto parte per 13 anni del Consiglio di vigilanza dell&#8217;Ordine degli Avvocati di Ginevra, di cui cinque anni come Presidente, gode di una riconosciuta esperienza nel diritto della professione legale. Oltre alle sue attivit\u00e0 professionali, \u00e8 impegnato a servire la societ\u00e0 attraverso la partecipazione attiva a diverse associazioni o fondazioni sociali e culturali.<\/p>\n\n\n\n<p>Parla e lavora in francese, inglese e tedesco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jean-Louis Collart vanta una solida formazione giuridica e una lunga esperienza nella consulenza ai clienti in materia commerciale e civile, nonch\u00e9 in materia di contenzioso, diritto delle successioni e protezione dei dati. \u00c8 stato ammesso all&#8217;albo degli avvocati di Ginevra nel 1988. Una volta superato l&#8217;esame di abilitazione, \u00e8 entrato a far parte di un [&hellip;]<\/p>\n","protected":false},"author":724,"featured_media":28394,"template":"","sector":[195],"country":[185,11267],"skill":[114,116,136,3047],"class_list":["post-28399","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-it","country-ch-it","country-geneve-it","skill-contenzioso","skill-contratti","skill-contratti-di-distribuzione","skill-privacy-and-data-security-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor\/28399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/users\/724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media\/28394"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media?parent=28399"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/sector?post=28399"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/country?post=28399"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/skill?post=28399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}