{"id":19643,"date":"2021-11-03T21:29:11","date_gmt":"2021-11-03T20:29:11","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/alan-notinger\/"},"modified":"2025-04-25T10:03:25","modified_gmt":"2025-04-25T08:03:25","slug":"alan-notinger","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/it\/network\/alan-notinger\/","title":{"rendered":"Alan Notinger"},"content":{"rendered":"<p>Alan si occupa di una vasta gamma di controversie commerciali e d&#8217;affari, tra cui controversie \u00a0riguardanti contratti, licenze, segreti commerciali, software per computer, beni e servizi, acquisizioni di aziende, questioni relative a creditori e debitori, partnership, pignoramenti, riscossioni, insolvenze e altri tipi di controversie aziendali. Si occupa anche di una variet\u00e0 di questioni di diritto del lavoro, tra cui controversie e reclami che riguardano la cessazione del rapporto di lavoro, accordi di non concorrenza e non divulgazione, contratti di lavoro, accordi di fine rapporto, risarcimenti del danno e altri tipi di questioni relative all&#8217;occupazione.<\/p>\n<p>Alan ha sede a Dallas, Texas ed \u00e8 ammesso ad esercitare in tutti i tribunali statali e federali dello Stato del Texas. \u00c8 membro dell&#8217;American Bar Association, State Bar of Texas, Dallas Bar Association e Association for Corporate Growth.<\/p>\n<p>Alan si \u00e8 laureato in legge presso la Duke University School of Law e si \u00e8 laureato presso la State University of New York a Binghamton.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alan si occupa di una vasta gamma di controversie commerciali e d&#8217;affari, tra cui controversie \u00a0riguardanti contratti, licenze, segreti commerciali, software per computer, beni e servizi, acquisizioni di aziende, questioni relative a creditori e debitori, partnership, pignoramenti, riscossioni, insolvenze e altri tipi di controversie aziendali. Si occupa anche di una variet\u00e0 di questioni di diritto [&hellip;]<\/p>\n","protected":false},"author":659,"featured_media":34336,"template":"","sector":[195],"country":[191,10786,12778],"skill":[114,111,147,166,135],"class_list":["post-19643","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-it","country-us-it","country-dallas-it","country-us-tx-it","skill-contenzioso","skill-arbitrato","skill-fallimentare","skill-lavoro","skill-recupero-credito"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor\/19643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/users\/659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media\/34336"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media?parent=19643"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/sector?post=19643"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/country?post=19643"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/skill?post=19643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}