{"id":15566,"date":"2020-04-07T12:30:41","date_gmt":"2020-04-07T10:30:41","guid":{"rendered":"https:\/\/www.legalmondo.com\/?p=15566"},"modified":"2020-04-07T13:56:44","modified_gmt":"2020-04-07T11:56:44","slug":"amazon-responsabilita-violazioni-marchi-marketplace","status":"publish","type":"post","link":"https:\/\/www.legalmondo.com\/it\/2020\/04\/amazon-responsabilita-violazioni-marchi-marketplace\/","title":{"rendered":"Quando Amazon \u00e8 responsabile per le violazioni dei marchi sul Marketplace?"},"content":{"rendered":"<p><strong>Riassunto<\/strong> \u2013 Cosa pu\u00f2 fare il titolare (o licenziatario) di un marchio se un terzo non autorizzato rivende su una piattaforma online i prodotti con il suo marchio? La questione \u00e8 stata analizzata nella sentenza C\u2011567\/18 del 2 aprile 2020, in cui la Corte di Giustizia dell\u2019Unione Europea ha confermato che le piattaforme che forniscono il servizio di deposito di prodotti (Amazon Marketplace, nel caso di specie) che violano un diritto di propriet\u00e0 intellettuale non sono responsabili per la violazione di tale diritto, salvo mettano in commercio i prodotti per conto proprio o siano a conoscenza della violazione. Al contrario, sono direttamente responsabili le piattaforme (come Amazon Retail) che partecipano alla distribuzione o rivendono direttamente i prodotti.<\/p>\n<hr \/>\n<p>Coty \u2013 azienda che distribuisce profumi ed \u00e8 titolare di una licenza europea sul marchio \u201cDavidoff\u201d \u2013 rilevava che <strong>sul Marketplace di Amazon dei venditori terzi offrivano in vendita dei profumi recanti il marchio \u201cDavidoff Hot Water\u201d<\/strong>, immessi in commercio nell\u2019Unione Europea senza il suo consenso.<\/p>\n<p>Dopo aver raggiunto un accordo con uno dei venditori, Coty agiva giudizialmente al fine di intimare ad Amazon di astenersi dallo stoccare o spedire tali profumi, a meno che gli stessi non fossero stati immessi in commercio nell\u2019Unione con il suo consenso. Sia il tribunale di primo grado, che la Corte d\u2019Appello successivamente adita respingevano l\u2019azione proposta da Coty, che proponeva ricorso per cassazione (\u201cRevision\u201d), a seguito del quale la questione veniva rimessa alla Corte di Giustizia dell\u2019Unione Europea.<\/p>\n<h2>Cos\u2019\u00e8 il Principio di esaurimento del Marchio<\/h2>\n<p>Il principio di esaurimento comunitario \u00e8 un principio previsto dal diritto dell&#8217;Unione Europea, secondo il quale, <strong>una volta messo in commercio un bene nel territorio dell&#8217;Unione Europea, il titolare del diritto di propriet\u00e0 industriale su quel bene specifico non pu\u00f2 pi\u00f9 limitarne l\u2019uso da parte di terzi<\/strong>.<\/p>\n<p>Questo principio ha efficacia <strong>soltanto se l&#8217;immissione del bene<\/strong> (il riferimento \u00e8 al singolo prodotto) sul mercato <strong>viene effettuata direttamente dal titolare del diritto, o con il suo consenso<\/strong> (per esempio tramite un operatore che ne detiene una licenza).<\/p>\n<p>Al contrario, se il bene viene immesso sul mercato da soggetti terzi senza il consenso del titolare, quest\u2019ultimo potr\u00e0 \u2013 esercitando i diritti di privativa sul marchio stabiliti dall\u2019art. 9, par. 3 del Regolamento UE 2017\/1001 \u2013 vietare l\u2019uso del marchio per l&#8217;immissione in commercio dei prodotti.<\/p>\n<p>Siccome i profumi in questione erano stati immessi sul mercato senza il consenso di Coty, questa poteva legittimamente impedire al venditore terzo di usare il marchio \u201cDavidoff\u201d per la loro commercializzazione. Con l\u2019azione giudiziaria proposta dinanzi alle corti tedesche e sfociata nella pronuncia della Corte di Giustizia UE, <strong>Coty ha cercato di far valere questo suo diritto anche nei confronti di Amazon, considerandola anch\u2019essa utilizzatrice del marchio e, pertanto, responsabile della violazione<\/strong>.<\/p>\n<h2>Il ruolo di Amazon<\/h2>\n<p>La soluzione del caso ruota attorno al ruolo di Amazon.<\/p>\n<p>La piattaforma, seppur fornisca agli utenti un motore di ricerca unico, ospita al suo interno due canali di vendita, profondamente diversi. <strong>Amazon Retail<\/strong> \u00e8 il canale attraverso cui il cliente conclude gli acquisti direttamente con la societ\u00e0 Amazon, la quale opera come rivenditrice dei prodotti previamente acquistati dai fornitori terzi.<\/p>\n<p>Su <strong>Amazon Marketplace<\/strong>, invece, vengono esposti prodotti di venditori terzi, che vengono acquistati dal cliente finale attraverso un contratto stipulato direttamente con il venditore, sul quale Amazon prende una percentuale a titolo di commissione, mentre il venditore si assume la responsabilit\u00e0 della vendita e gestisce in autonomia i prezzi dei prodotti.<\/p>\n<p>Secondo i due giudici di merito tedeschi che hanno rigettato in prima e seconda istanza le richieste di Coty, Amazon Marketplace svolge essenzialmente la funzione di depositario, che non fornisce alcuna assistenza all\u2019offerta di vendita, alla vendita e all\u2019immissione in commercio dei prodotti che ha in deposito.<\/p>\n<p>Coty, al contrario, sostiene che Amazon Marketplace, offrendo svariati servizi nell\u2019ambito dell\u2019immissione in commercio dei prodotti (tra cui: comunicazione con i potenziali clienti ai fini della vendita dei prodotti; fornitura della piattaforma attraverso la quale viene concluso il contratto di vendita e promozione continuativa dei prodotti, sia sul proprio sito web, sia mediante annunci pubblicitari nel motore di ricerca Google), possa essere considerata come \u201cutilizzatrice\u201d del marchio, ai sensi dell\u2019art. 9, par. 3 del Regolamento UE 2017\/1001.<\/p>\n<h2>La decisione della Corte di Giustizia UE<\/h2>\n<p>Nelle conclusioni depositate nel novembre 2019, <strong>l\u2019Avvocato Generale<\/strong> Campos Sanchez-Bordona <strong>aveva<\/strong> <strong>suggerito alla Corte di distinguere tra i meri depositari dei beni<\/strong>, da considerare come non \u201cutilizzatori\u201d del marchio ai fini del Regolamento 2017\/1001; <strong>e i soggetti che<\/strong> \u2013 oltre a fornire il servizio di deposito \u2013<strong>partecipano attivamente alla distribuzione dei prodotti<\/strong>. Questi ultimi, alla luce dell\u2019art. 9, par. 3, lett. b) del Regolamento 2017\/1001, dovrebbero essere considerati come \u201cutilizzatori\u201d del marchio, e pertanto direttamente responsabili in caso di violazioni.<\/p>\n<p><strong>Il Bundesgerichtshof (Corte federale di giustizia tedesca)<\/strong>, per\u00f2, <strong>nel sottoporre il quesito<\/strong> alla CGUE <strong>si era gi\u00e0 parzialmente dato la risposta, definendo Amazon Marketplace come un soggetto che si limita \u201cal magazzinaggio dei prodotti di cui trattasi, senza averli offerti in vendita o averli immessi in commercio\u201d, entrambe operazioni svolte unicamente dal venditore.<\/strong><\/p>\n<p>La Corte di Giustizia UE ha deciso sulla base di alcuni propri precedenti, in cui aveva gi\u00e0 affermato che:<\/p>\n<ul>\n<li>il concetto di \u201c<strong>utilizzo\u201d implica, quanto meno, l\u2019uso del segno nell\u2019ambito della comunicazione commerciale<\/strong>. Un soggetto, quindi, pu\u00f2 permettere ai propri clienti di fare uso del marchio, senza essere configurato esso stesso \u201cutilizzatore\u201d (v. Google vs Louis Vuitton, da <a href=\"http:\/\/curia.europa.eu\/juris\/document\/document.jsf?text=&amp;docid=83961&amp;pageIndex=0&amp;doclang=IT&amp;mode=lst&amp;dir=&amp;occ=first&amp;part=1&amp;cid=1289962\" target=\"_blank\" rel=\"noopener noreferrer\">C\u2011236\/08 a C\u2011238\/08<\/a>, punto 56).<\/li>\n<li><strong>Con riferimento alle piattaforme di commercio on-line, l\u2019uso del segno identico o simile a un marchio viene posto in essere dai clienti-venditori<\/strong>, e non dal gestore della piattaforma (v. L\u2019Or\u00e9al vs eBay, <a href=\"http:\/\/curia.europa.eu\/juris\/document\/document.jsf?text=&amp;docid=107261&amp;pageIndex=0&amp;doclang=IT&amp;mode=lst&amp;dir=&amp;occ=first&amp;part=1&amp;cid=1289962\" target=\"_blank\" rel=\"noopener noreferrer\">C\u2011324\/09<\/a>, punto 103).<\/li>\n<li>Il <strong>prestatore di servizi che esegue semplicemente una parte tecnica del processo di produzione<\/strong> del prodotto finale, <strong>non pu\u00f2 essere qualificato come \u201cutilizzatore\u201d di eventuali segni presenti sui prodotti finali<\/strong> (v. Frisdranken vs Red Bull, <a href=\"http:\/\/curia.europa.eu\/juris\/document\/document.jsf?text=&amp;docid=116683&amp;pageIndex=0&amp;doclang=IT&amp;mode=lst&amp;dir=&amp;occ=first&amp;part=1&amp;cid=1289962\" target=\"_blank\" rel=\"noopener noreferrer\">C\u2011119\/10<\/a>, punto 30. Frisdranken era un\u2019impresa la cui attivit\u00e0 principale consisteva nel riempimento di lattine, fornite da un terzo, gi\u00e0 provviste di segni simili a marchi registrati).<\/li>\n<\/ul>\n<p>Sulla scorta di questi precedenti e della qualifica di Amazon Marketplace fornita dal giudice del rinvio, la Corte ha sancito che un soggetto che tenga in deposito per conto di un terzo dei prodotti che violano un diritto di marchio, se non \u00e8 a conoscenza di tale violazione e non li mette in offre in vendita n\u00e9 li immette in commercio, non sta facendo uso del segno e, pertanto, non \u00e8 responsabile nei confronti del titolare dei diritti su quel marchio.<\/p>\n<h2>Conclusioni<\/h2>\n<p>Dopo che in passato Coty era stata protagonista di una sentenza storica in materia (C-230\/16 \u2013 <a href=\"https:\/\/www.legalmondo.com\/it\/2017\/12\/corte-di-giustizia-ue-ammette-la-restrizione-alle-vendite-online-sentenza-coty\/\" target=\"_blank\" rel=\"noopener noreferrer\">qui il commento<\/a>), in questo caso la decisione della Corte di Giustizia UE ha confermato lo <em>status quo<\/em>, lasciando per\u00f2 aperta la porta ad un cambiamento in un futuro prossimo.<\/p>\n<p>Alcune impressioni sulla sentenza, prima di passare ad alcuni consigli pratici:<\/p>\n<ul>\n<li>La CGUE <strong>non ha definito in termini positivi i criteri per valutare se una piattaforma online svolga attivit\u00e0 sufficiente per essere considerata utilizzatrice del segno<\/strong> (e quindi responsabile per l\u2019eventuale violazione del marchio registrato). La ragione di questa scelta, probabilmente, sta nella circostanza che i criteri dettati avrebbero potuto essere applicati (a ben vedere anche contro le diverse societ\u00e0 del gruppo Amazon) a macchia di leopardo dai diversi giudici nazionali degli Stati Membri, pregiudicando l\u2019applicazione uniforme del diritto europeo.<\/li>\n<li><strong>Un\u2019eventuale pronuncia in senso opposto della CGUE avrebbe avuto un impatto dirompente<\/strong> non solo sul Marketplace di Amazon, ma su tutti gli operatori online, perch\u00e9 li avrebbe resi direttamente responsabili delle violazioni di diritti di propriet\u00e0 intellettuale posti in essere da soggetti terzi.<\/li>\n<li>Nel caso in cui i prodotti oggetto della sentenza fossero stati venduti attraverso <strong>Amazon Retail, non vi sarebbe stato alcun dubbio sulla responsabilit\u00e0 di Amazon<\/strong>: attraverso questo canale, infatti, le vendite sono concluse direttamente tra Amazon e il cliente finale, a differenza di quanto avviene attraverso Amazon Marketplace.<\/li>\n<li>La Corte <strong>non ha valutato se: (i) Amazon potesse essere considerata indirettamente responsabile <\/strong>ai sensi dell\u2019 art. 14, paragrafo 1, della Direttiva UE 2000\/31,<strong> in quanto \u00abhost\u00bb che \u2013 pur essendo al corrente dell\u2019attivit\u00e0 illecita \u2013 non l\u2019ha impedita; (ii) <\/strong>ai sensi dell\u2019articolo 11, della Direttiva UE 2004\/48,<strong> Coty avrebbe potuto agire nei suoi confronti, in quanto intermediario i cui servizi sono utilizzati da terzi per violare un diritto di propriet\u00e0 intellettuale<\/strong>. Non \u00e8 quindi da escludere che Amazon possa essere ritenuta (indirettamente) responsabile per le violazioni commesse,anche sul Marketplace: questo aspetto dovr\u00e0 essere approfondito caso per caso.<\/li>\n<\/ul>\n<h2>Consigli pratici<\/h2>\n<p>Cosa pu\u00f2 fare il titolare (o licenziatario) di un marchio che trovi su una piattaforma online prodotti a proprio marchio rivenduti da terzi non autorizzati?<\/p>\n<ol>\n<li><strong>Raccogliere quante pi\u00f9 prove possibili della violazione<\/strong> in atto: la dimostrazione della violazione \u00e8 uno degli aspetti pi\u00f9 problematici dei giudizi di aventi ad oggetto la violazione di diritti di propriet\u00e0 industriale.<\/li>\n<li>Rivolgersi ad un legale esperto in materia per inviare una <strong>diffida<\/strong> al venditore non autorizzato, chiedendo la <strong>rimozione dei prodotti<\/strong> <strong>dalla piattaforma <\/strong>e il <strong>risarcimento dei danni subiti<\/strong>.<\/li>\n<li>In caso di mancata rimozione dei prodotti dal marketplace, potr\u00e0 <strong>valutare<\/strong> \u2013 sempre affidandosi ad un legale \u2013 la migliore forma per avanzare le medesime richieste anche in <strong>via giudiziale<\/strong>.<\/li>\n<li>Nonostante alla luce della pronuncia appena vista la piattaforma online (a meno che non svolga un ruolo attivo nella rivendita dei beni) continui a non essere direttamente responsabile, si suggerisce di valutare <strong>l\u2019invio della diffida anche alla piattaforma<\/strong>, per aumentare la pressione sul venditore non autorizzato.<\/li>\n<li>L\u2019invio della diffida anche alla piattaforma online potr\u00e0 servire anche per sostenere \u2013 specialmente in caso di reiterazione della violazione \u2013 una sua<strong> responsabilit\u00e0 indiretta per omissione nella vigilanza <\/strong>che, come visto al punto 4) del precedente elenco, non \u00e8 stata esclusa dalla Corte di Giustizia UE.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Riassunto \u2013 Cosa pu\u00f2 fare il titolare (o licenziatario) di un marchio se un terzo non autorizzato rivende su una piattaforma online i prodotti con il suo marchio? La questione \u00e8 stata analizzata nella sentenza C\u2011567\/18 del 2 aprile 2020, in cui la Corte di Giustizia dell\u2019Unione Europea ha confermato che le piattaforme che forniscono [&hellip;]<\/p>\n","protected":false},"author":404,"featured_media":15568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[211,215],"tags":[4526,217],"class_list":["post-15566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecommerce-it","category-intellectual-property-it","tag-europe-it","tag-italy-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/posts\/15566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/users\/404"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/comments?post=15566"}],"version-history":[{"count":4,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/posts\/15566\/revisions"}],"predecessor-version":[{"id":15580,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/posts\/15566\/revisions\/15580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media\/15568"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/media?parent=15566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/categories?post=15566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalmondo.com\/it\/wp-json\/wp\/v2\/tags?post=15566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}