{"id":18223,"date":"2016-09-27T09:42:19","date_gmt":"2016-09-27T07:42:19","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/renata-antiquera\/"},"modified":"2025-08-18T23:22:02","modified_gmt":"2025-08-18T21:22:02","slug":"renata-antiquera","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/es\/network\/renata-antiquera\/","title":{"rendered":"Renata Antiquera"},"content":{"rendered":"<p>Renata Antiquera es una abogada brasile\u00f1a con m\u00e1s de 30 a\u00f1os de experiencia, que trabaja principalmente en representaci\u00f3n de empresas extranjeras, fondos de capital de riesgo, private equity e inversores privados, principalmente de Europa y Am\u00e9rica Latina, en operaciones de fusiones y adquisiciones de tama\u00f1o medio, joint ventures, establecimiento de filiales locales, estructuras de inversi\u00f3n, as\u00ed como en la creaci\u00f3n de redes de distribuci\u00f3n, agencias o franquicias en Brasil.<\/p>\n<p>Su pr\u00e1ctica es integral e incluye asuntos corporativos y de gobernanza, redacci\u00f3n y negociaci\u00f3n de contratos, operaciones inmobiliarias, protecci\u00f3n de datos y derecho digital, marketing jur\u00eddico y patrocinios. En resumen, es capaz de ayudar a sus clientes en todas las cuestiones transaccionales relacionadas con sus negocios en todos los sectores.<\/p>\n<p>Renata es socia de Renata Antiquera Business Law, en S\u00e3o Paulo, Brasil, y act\u00faa como Of Counsel para Pereira Pulici Advogados y otros despachos. Es licenciada en Derecho por la Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (1993) y ha realizado cursos de especializaci\u00f3n en Derecho Procesal Civil y Mercados de Capitales.<\/p>\n<p>Renata es miembro honorario de la AIJA y fue miembro activo de la Secci\u00f3n de Derecho Internacional de la American Bar Association. Renata ha organizado y ha sido ponente en varios seminarios internacionales y paneles de congresos.<\/p>\n<p>Habla con fluidez portugu\u00e9s, ingl\u00e9s, franc\u00e9s e italiano, y entiende y lee espa\u00f1ol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renata Antiquera is a Brazilian lawyer that has more than 20 years of experience working mostly on behalf of foreign companies, venture capital, private equity and private investors, mainly from Europe and Latin America, on mid-market mergers and acquisitions, joint-ventures, investment structures, and setting up distribution, agency or franchise structures in Brazil. <\/p>\n","protected":false},"author":57,"featured_media":9210,"template":"","sector":[383],"country":[550,595],"skill":[410,389,411,391],"class_list":["post-18223","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-es","country-br-es","country-sao-paulo-es","skill-contracts-es","skill-distribution-agreements-es","skill-derecho-societario","skill-ma-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/vendor\/18223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/users\/57"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/media\/9210"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/media?parent=18223"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/sector?post=18223"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/country?post=18223"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/skill?post=18223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}