{"id":4784,"date":"2017-11-27T22:11:57","date_gmt":"2017-11-27T21:11:57","guid":{"rendered":"https:\/\/www.legalmondo.com\/?p=4784"},"modified":"2020-01-05T21:51:08","modified_gmt":"2020-01-05T20:51:08","slug":"italia-duracion-de-la-sociedad-limitada-y-separacion-del-socio","status":"publish","type":"post","link":"https:\/\/www.legalmondo.com\/es\/2017\/11\/italia-duracion-de-la-sociedad-limitada-y-separacion-del-socio\/","title":{"rendered":"Italia &#8211; Duraci\u00f3n de la sociedad limitada y separaci\u00f3n del socio"},"content":{"rendered":"<p>Como para todos los contratos de duraci\u00f3n indeterminada, tambi\u00e9n <strong>para las<\/strong> <strong>sociedades limitadas<\/strong> (s.r.l.), <strong>la ley italiana prev\u00e9 la posibilidad de separaci\u00f3n del socio<\/strong>.<\/p>\n<p>El art\u00edculo 2473 del C\u00f3digo Civil italiano (C. c.) reconoce al socio el <strong>derecho a separarse de la sociedad<\/strong>, adem\u00e1s de en los casos expresamente previstos en la escritura de constituci\u00f3n, tambi\u00e9n cuando el mismo no haya permitido el cambio del objeto social o del tipo de sociedad, su fusi\u00f3n o escisi\u00f3n, la revocaci\u00f3n de la situaci\u00f3n de liquidaci\u00f3n, el traslado del domicilio al extranjero, la eliminaci\u00f3n de una o m\u00e1s causas de separaci\u00f3n previstas en la escritura de constituci\u00f3n o en los casos de operaciones que conlleven una sustancial modificaci\u00f3n del objeto social determinado en la escritura de constituci\u00f3n o de los derechos particulares atribuidos al socio en virtud del art. 2468 del C.c.<\/p>\n<p>Adem\u00e1s de en las hip\u00f3tesis anteriormente mencionadas, el derecho de separaci\u00f3n puede tambi\u00e9n ser ejercitado cuando:<\/p>\n<ul>\n<li>La escritura de constituci\u00f3n prevea la no transmisibilidad de la participaci\u00f3n o subordine su transmisibilidad a la aprobaci\u00f3n de los \u00f3rganos sociales \u00a0(art. 2469 C.c.).<\/li>\n<li>Se acuerde el aumento del capital social con emisi\u00f3n de nuevas participaciones en favor de terceros (art. 2481 <em>bis<\/em> c.).<\/li>\n<li>Se introduzcan, supriman o modifiquen de manera relevante cl\u00e1usulas arbitrales contenidas en la escritura de constituci\u00f3n (art. 36 D.Lg. 5\/2003).<\/li>\n<li>La sociedad matriz haya sido condenada en base al art. 2497 <em>quater<\/em> c.<\/li>\n<\/ul>\n<p><strong>Adem\u00e1s de dichas hip\u00f3tesis<\/strong>, siempre es v\u00e1lida la regla general, contenida en el art. 2473.2 del C. c., por la que <strong>el socio siempre puede separarse<\/strong>, dando un <strong>preaviso de 180 d\u00edas<\/strong> (o m\u00e1s si lo dispone la escritura de constituci\u00f3n) <strong>cuando la sociedad haya sido creada por tiempo indeterminado<\/strong>.<\/p>\n<p>Se ha discutido ampliamente, y todav\u00eda se discute, sobre la posibilidad para el socio de recurrir a dicha hip\u00f3tesis de separaci\u00f3n <em>ad nutum<\/em> cuando la sociedad haya sido constituida por un plazo determinado pero superior a la duraci\u00f3n de la vida humana.<\/p>\n<p>Sobre la cuesti\u00f3n, la jurisprudencia ha subrayado que una duraci\u00f3n superior a la media de la vida humana, da lugar a la aplicaci\u00f3n de la disciplina prevista para las sociedades a tiempo indeterminado.<\/p>\n<p>La <strong>Corte de Casaci\u00f3n<\/strong>, con la decisi\u00f3n n\u00fam. 9662 del 22 de abril de 2013, <strong>ha reconocido la similitud \u00a0de una sociedad constituida con duraci\u00f3n hasta el 2100 con una sociedad de duraci\u00f3n ilimitada<\/strong>, precisando que en presencia de un plazo tan alejado en el tiempo, incluso superando la perspectiva de vida de la persona f\u00edsica y la operatividad de un sujeto colectivo, se admite la separaci\u00f3n <em>ad nutum<\/em> prevista para las sociedades a tiempo indeterminado, teniendo en cuenta el hecho de que el legislador siempre ha considerado en modo negativo los v\u00ednculos perpetuos.<\/p>\n<p>Seg\u00fan los jueces, la previsi\u00f3n de un plazo de duraci\u00f3n del sujeto colectivo tiene la funci\u00f3n de establecer si la prespectiva de vida de la sociedad es adecuada con respecto al proyecto que se desea conseguir.<\/p>\n<p>Por tanto, la fijaci\u00f3n de un plazo largo de duraci\u00f3n de la sociedad, podr\u00eda impedir que se realizase la efectiva voluntad de las partes del contrato social por lo que respecta a la elecci\u00f3n entre sociedad a tiempo determidado y sociedad a tiempo indeterminado.<\/p>\n<p>Po ello, no podr\u00eda excluirse que la indicaci\u00f3n de una duraci\u00f3n desproporcionada respecto a la vida de los socios o al objeto social que se quiere persiguir, tenga en realidad la intenci\u00f3n de eludir los efectos que se producir\u00edan con una declaraci\u00f3n expl\u00edcita de duraci\u00f3n indeterminada, la cual podr\u00eda \u00fanicamente ser corregida mediante una interpretaci\u00f3n que garantizase al socio las tutelas previstas por el ordenamiento con referencia a las sociedades con duraci\u00f3n ilimitada.<\/p>\n<p><strong>La l\u00ednea seguida por la Corte de Casaci\u00f3n ha sido respaldada tambi\u00e9n por los Tribunales<\/strong>.<\/p>\n<p>En particular, las secciones especializadas en materia de empresa del Tribunal de Roma (sentencia del 22 de octubre de 2015) y del Tribunal de Tur\u00edn (Auto del 5 de mayo de 2017) han reconocido el derecho de separaci\u00f3n con preaviso para sociedades con una duraci\u00f3n de hasta el 2100, considerando dicha duraci\u00f3n como ilimitada.<\/p>\n<p>El Tribunal piamont\u00e9s se ha servido de las argumentaciones de la Corte de Casaci\u00f3n, aplicando el principio seg\u00fan el cual deben considerarse constituidas a tiempo indeterminado no solo las s.r.l. con duraci\u00f3n superior a la normal vida humana, sino tambi\u00e9n las s.r.l. que hayan sido constituidas por un plazo muy amplio, con las que se considera superado el horizonte temporal razonable necesario para la consecuci\u00f3n del objeto social.<\/p>\n<p>Dicha orientaci\u00f3n jurisprudencial obliga a los operadores del derecho a <strong>prestar particular atenci\u00f3n a la duraci\u00f3n temporal de las sociedades limitadas<\/strong>, con el fin de evitar una aplicaci\u00f3n m\u00e1s amplia y generalizada, respecto a lo deseado, de los derechos reconocidos a los socios de una s.r.l. a tiempo indeterminado.<\/p>\n<p><em>El autor de este art\u00edculo es Giovanni Izzo.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como para todos los contratos de duraci\u00f3n indeterminada, tambi\u00e9n para las sociedades limitadas (s.r.l.), la ley italiana prev\u00e9 la posibilidad de separaci\u00f3n del socio. El art\u00edculo 2473 del C\u00f3digo Civil italiano (C. c.) reconoce al socio el derecho a separarse de la sociedad, adem\u00e1s de en los casos expresamente previstos en la escritura de constituci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":5889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[496],"tags":[734],"class_list":["post-4784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-es","tag-italy-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/posts\/4784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/comments?post=4784"}],"version-history":[{"count":2,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/posts\/4784\/revisions"}],"predecessor-version":[{"id":12456,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/posts\/4784\/revisions\/12456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/media\/5889"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/media?parent=4784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/categories?post=4784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalmondo.com\/es\/wp-json\/wp\/v2\/tags?post=4784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}