{"id":29969,"date":"2021-11-03T21:29:11","date_gmt":"2021-11-03T20:29:11","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/alan-notinger\/"},"modified":"2025-04-25T10:04:41","modified_gmt":"2025-04-25T08:04:41","slug":"alan-notinger","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/de\/network\/alan-notinger\/","title":{"rendered":"Alan Notinger"},"content":{"rendered":"<p>Alan befasst sich mit einem breiten Spektrum von Handels- und Gesch\u00e4ftsstreitigkeiten, einschlie\u00dflich Streitigkeiten im Zusammenhang mit Vertr\u00e4gen, Lizenzen, Gesch\u00e4ftsgeheimnissen, Computersoftware, Waren und Dienstleistungen, Unternehmensk\u00e4ufen, Gl\u00e4ubiger- und Schuldnerangelegenheiten, Partnerschaften, Zwangsvollstreckungen, Inkasso, Insolvenzen und anderen Arten von Gesch\u00e4ftsstreitigkeiten. Er befasst sich auch mit einer Vielzahl von arbeitsrechtlichen Angelegenheiten, einschlie\u00dflich Streitigkeiten und Anspr\u00fcchen im Zusammenhang mit der Beendigung des Arbeitsverh\u00e4ltnisses, Wettbewerbsverboten und Geheimhaltungsvereinbarungen, Arbeitsvertr\u00e4gen, Abfindungsvereinbarungen, Schadensersatz und anderen Arten von arbeitsrechtlichen Angelegenheiten.<\/p>\n<p>Alan hat seinen Sitz in Dallas, Texas, und ist vor allen einzelstaatlichen und bundesstaatlichen Gerichten des Bundesstaates Texas als Anwalt zugelassen. Er ist Mitglied der American Bar Association, State Bar of Texas, Dallas Bar Association und Association for Corporate Growth.<\/p>\n<p>Alan erhielt seinen Abschluss in Jura von der Duke University School of Law und seinen Bachelor-Abschluss von der State University of New York in Binghamton.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alan befasst sich mit einem breiten Spektrum von Handels- und Gesch\u00e4ftsstreitigkeiten, einschlie\u00dflich Streitigkeiten im Zusammenhang mit Vertr\u00e4gen, Lizenzen, Gesch\u00e4ftsgeheimnissen, Computersoftware, Waren und Dienstleistungen, Unternehmensk\u00e4ufen, Gl\u00e4ubiger- und Schuldnerangelegenheiten, Partnerschaften, Zwangsvollstreckungen, Inkasso, Insolvenzen und anderen Arten von Gesch\u00e4ftsstreitigkeiten. Er befasst sich auch mit einer Vielzahl von arbeitsrechtlichen Angelegenheiten, einschlie\u00dflich Streitigkeiten und Anspr\u00fcchen im Zusammenhang mit der Beendigung [&hellip;]<\/p>\n","protected":false},"author":659,"featured_media":34335,"template":"","sector":[10894],"country":[11454,12777,10967],"skill":[10969,11013,10892,10911,10974],"class_list":["post-29969","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-en-de","country-dallas-de","country-us-tx-de","country-us-de","skill-labor-de","skill-credit-collection-de","skill-litigation-de","skill-arbitration-de","skill-insolvency-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/vendor\/29969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/users\/659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media\/34335"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media?parent=29969"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/sector?post=29969"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/country?post=29969"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/skill?post=29969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}