{"id":29825,"date":"2024-07-24T19:49:10","date_gmt":"2024-07-24T17:49:10","guid":{"rendered":"https:\/\/www.legalmondo.com\/network\/thomas-kriense\/"},"modified":"2024-07-24T19:54:40","modified_gmt":"2024-07-24T17:54:40","slug":"thomas-kriense","status":"publish","type":"vendor","link":"https:\/\/www.legalmondo.com\/de\/network\/thomas-kriense\/","title":{"rendered":"Thomas Kriense"},"content":{"rendered":"<p>Thomas ist seit 2012 als Rechtsanwalt t\u00e4tig. Nach seinem Abschluss an der juristischen Fakult\u00e4t der Universit\u00e4t Leiden sammelte er Erfahrungen in IP-Boutiquen und mittelst\u00e4ndischen Kanzleien. Er arbeitete lange f\u00fcr die BREIN-Stiftung (&#8222;Stichting BREIN&#8220;), eine Organisation, die sich f\u00fcr den Schutz von Urheberrechten auf dem digitalen Markt einsetzt. Heute f\u00fchrt er eine Praxis f\u00fcr Rechtsstreitigkeiten und Beratung und konzentriert sich haupts\u00e4chlich auf geistiges Eigentum, IT, Medien und Datenschutzrecht.<\/p>\n<p>Thomas ist spezialisiert auf komplexe Fragen des geistigen Eigentums, die Ausarbeitung von (IT-)Vertr\u00e4gen und die Zusammenarbeit mit Kunden bei der Entwicklung von Strategien zum Schutz des geistigen Eigentums, zur Verwertung von Daten und zum Schutz von Daten. In einer Gesellschaft, in der der Datenschutz aufgrund von Digitalisierung und Big Data immer wichtiger wird, konzentriert sich Thomas auch auf die Einhaltung von Vorschriften in diesem Bereich.<\/p>\n<p>Thomas spricht flie\u00dfend Englisch und Niederl\u00e4ndisch und hat Grundkenntnisse in Deutsch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thomas ist seit 2012 als Rechtsanwalt t\u00e4tig. Nach seinem Abschluss an der juristischen Fakult\u00e4t der Universit\u00e4t Leiden sammelte er Erfahrungen in IP-Boutiquen und mittelst\u00e4ndischen Kanzleien. Er arbeitete lange f\u00fcr die BREIN-Stiftung (&#8222;Stichting BREIN&#8220;), eine Organisation, die sich f\u00fcr den Schutz von Urheberrechten auf dem digitalen Markt einsetzt. Heute f\u00fchrt er eine Praxis f\u00fcr Rechtsstreitigkeiten und [&hellip;]<\/p>\n","protected":false},"author":749,"featured_media":34415,"template":"","sector":[10894],"country":[11239,11060],"skill":[11062,10891,11061,11022,10892],"class_list":["post-29825","vendor","type-vendor","status-publish","has-post-thumbnail","hentry","sector-legal-en-de","country-amsterdam-de","country-nl-de","skill-privacy-and-data-security-de","skill-intellectual-property-de","skill-information-technology-de","skill-media-de","skill-litigation-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/vendor\/29825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/vendor"}],"about":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/types\/vendor"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/users\/749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media\/34415"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media?parent=29825"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/sector?post=29825"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/country?post=29825"},{"taxonomy":"skill","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/skill?post=29825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}