{"id":21171,"date":"2023-01-05T09:00:00","date_gmt":"2023-01-05T08:00:00","guid":{"rendered":"https:\/\/www.legalmondo.com\/2022\/12\/african-continental-free-trade-area-afcfta\/"},"modified":"2023-01-15T17:10:58","modified_gmt":"2023-01-15T16:10:58","slug":"afrikanische-kontinentale-freihandelszone-afcfta","status":"publish","type":"post","link":"https:\/\/www.legalmondo.com\/de\/2023\/01\/afrikanische-kontinentale-freihandelszone-afcfta\/","title":{"rendered":"Die Afrikanische Kontinentale Freihandelszone (AfCFTA)\ufffc"},"content":{"rendered":"<p>Nach mehr als 30 Jahren Verhandlungen blickt die Welt nun auf das <strong>erste panafrikanische Handelsabkommen<\/strong>, welches 2019 in Kraft getreten ist: <strong>Die Afrikanische Kontinentale Freihandelszone (African Continental Free Trade Area &#8211; AfCFTA). <\/strong><\/p>\n<p>Afrika ist mit seinen 55 L\u00e4ndern und rund 1,3 Milliarden Einwohnern nach Asien der zweitgr\u00f6\u00dfte Kontinent der Welt. Das Potenzial des Kontinents ist enorm: Mehr als 50 % der afrikanischen Bev\u00f6lkerung ist unter 20 Jahre alt, und die Bev\u00f6lkerung w\u00e4chst weltweit am schnellsten. Bis 2050 wird voraussichtlich jedes vierte Neugeborene aus Afrika stammen. Dar\u00fcber hinaus ist der Kontinent reich an fruchtbaren B\u00f6den und Rohstoffen.<\/p>\n<p>F\u00fcr westliche Investoren hat Afrika in den letzten Jahren erheblich an Bedeutung gewonnen. So ist ein beachtliches internationales Handelsvolumen entstanden, das nicht zuletzt durch die 2017 von den G20-Staaten verabschiedete Initiative \u201eCompact with Africa\u201c, auch bekannt als \u201eMarshallplan mit Afrika\u201c, gef\u00f6rdert wird. Der Fokus liegt auf dem Ausbau der wirtschaftlichen Zusammenarbeit Afrikas mit den G20-L\u00e4ndern durch die St\u00e4rkung privater Investitionen.<\/p>\n<p>Zugleich stagnierte bislang jedoch der innerafrikanische Handel: Teilweise noch bestehende hohe innerafrikanische Z\u00f6lle, nichttarif\u00e4re Handelshemmnisse (non-tariff barriers &#8211; NTBs), schwache Infrastruktur, Korruption, schwerf\u00e4llige B\u00fcrokratie sowie intransparente und inkonsistente Regulierungen sorgten daf\u00fcr, dass sich die interregionalen Exporte kaum entwickeln konnten und zuletzt nur 17\u00a0% des innerafrikanischen Handels und nur 0,36\u00a0% des Welthandels ausmachten. Schon lange hatte sich deshalb die Afrikanische Union (AU) die Schaffung einer gemeinsamen Handelszone auf ihre Agenda gesetzt.<\/p>\n<h2><strong>Was verbirgt sich hinter AfCFTA?<\/strong><\/h2>\n<p>Der Errichtung einer panafrikanischen Handelszone gingen jahrzehntelange Verhandlungen voraus, welche schlie\u00dflich in das Inkrafttreten des AfCFTA am 30. Mai 2019 m\u00fcndeten.<\/p>\n<p>Das AfCFTA ist eine von ihren Mitgliedern errichtete Freihandelszone, die (mit Ausnahme Eritreas) den gesamten afrikanischen Kontinent umfasst und damit, gemessen an der Zahl der Mitgliedsstaaten nach der Welthandelsorganisation (World Trade Organization &#8211; WTO) die gr\u00f6\u00dfte Freihandelszone der Welt ist.<\/p>\n<p>Die Ausgestaltung des gemeinsamen Marktes war Gegenstand mehrerer Einzelverhandlungen, die in den Phasen I und II gef\u00fchrt wurden.<\/p>\n<p><strong>Phase I umfasst die Verhandlungen zu drei Protokollen und ist nahezu abgeschlossen.<\/strong><\/p>\n<h2><strong>Das Protokoll \u00fcber den Handel mit Waren<\/strong><\/h2>\n<p>Dieses Protokoll sieht die <strong>Abschaffung von 90\u00a0% aller innerafrikanischen Z\u00f6lle in allen Warenkategorien innerhalb von f\u00fcnf Jahren nach Inkrafttreten vor<\/strong>. Davon k\u00f6nnen bis zu 7\u00a0% der Waren als sensible Waren eingestuft werden, f\u00fcr die ein Zeitraum von zehn Jahren f\u00fcr die Beseitigung der Z\u00f6lle gilt. F\u00fcr die am wenigsten entwickelten L\u00e4nder (Least Developed Countries &#8211; LDCs) wird die Vorbereitungszeit von f\u00fcnf auf zehn Jahre und f\u00fcr sensible Waren von zehn auf dreizehn Jahre verl\u00e4ngert, sofern sie ihren Bedarf nachweisen. Die restlichen 3\u00a0% der Z\u00f6lle sind vollst\u00e4ndig vom Zollabbau ausgenommen.<\/p>\n<p>Voraussetzung f\u00fcr den Zollabbau ist die klare Abgrenzung der Ursprungsregeln. Andernfalls k\u00f6nnten Einfuhren aus Drittl\u00e4ndern von den ausgehandelten Zollvorteilen profitieren. \u00dcber die meisten Ursprungsregeln ist bereits eine Einigung erzielt worden.<\/p>\n<h2><strong>Das Protokoll \u00fcber den Handel mit Dienstleistungen<\/strong><\/h2>\n<p>Die AU-Generalversammlung hat sich bisher auf <strong>f\u00fcnf Schwerpunktbereiche <\/strong>(Verkehr, Kommunikation, Tourismus, Finanz- und Unternehmensdienstleistungen) <strong>und Leitlinien<\/strong> f\u00fcr die entsprechenden Verpflichtungen geeinigt. 47 AU-Mitgliedsstaaten haben bereits ihre Angebote f\u00fcr spezifische Verpflichtungen vorgelegt und die \u00dcberpr\u00fcfung von 28 von ihnen ist abgeschlossen. Dar\u00fcber hinaus sind die Verhandlungen, beispielsweise \u00fcber die Anerkennung von Berufsqualifikationen, noch nicht abgeschlossen.<\/p>\n<h2><strong>Das Protokoll \u00fcber die Streitbeilegung<\/strong><\/h2>\n<p>Mit dem Protokoll \u00fcber Regeln und Verfahren f\u00fcr die Streitbeilegung schafft das AfCFTA ein <strong>Streitbeilegungssystem nach dem Vorbild der WTO-Streitbeilegungsvereinbarung<\/strong>. Das Streitbeilegungsgremium (Dispute Settlement Body &#8211; DSB) verwaltet das AfCFTA-Streitbeilegungsprotokoll und setzt ein Schiedsgericht (Adjudicating Panel &#8211; Panel) und ein Berufungsgremium (Appellate Body &#8211; AB) ein. Das DSB setzt sich aus einem Vertreter jedes Mitgliedstaates zusammen und wird t\u00e4tig, sobald es zwischen den Vertragsstaaten Meinungsverschiedenheiten \u00fcber die Auslegung und\/oder Anwendung des Abkommens in Bezug auf ihre Rechte und Pflichten gibt.<\/p>\n<p>F\u00fcr die verbleibende <strong>Phase II <\/strong>sind Verhandlungen \u00fcber <strong>Investitions- und Wettbewerbspolitik,<\/strong> <strong>Fragen des geistigen Eigentums, Online-Handel sowie Frauen und Jugend im Handel <\/strong>geplant, deren Ergebnisse in weitere Protokolle einflie\u00dfen werden.<\/p>\n<h2><strong>Die Umsetzung des AfCFTA<\/strong><\/h2>\n<p>Grunds\u00e4tzlich kann der Handel im Rahmen eines Handelsabkommens erst dann beginnen, wenn der rechtliche Rahmen endg\u00fcltig steht. Die Staats- und Regierungschefs der AU haben jedoch im Dezember 2020 vereinbart, dass der Handel mit solchen Waren, f\u00fcr die die Verhandlungen abgeschlossen sind, beginnen kann. Im Rahmen dieser <strong>\u00dcbergangsregelung<\/strong> fand nach einer pandemiebedingten Verschiebung am <strong>4. Januar 2021 die erste AfCFTA-Handelsabwicklung<\/strong> von Ghana nach S\u00fcdafrika statt.<\/p>\n<h2><strong>Bausteine der AfCFTA<\/strong><\/h2>\n<p>Alle 55 Mitglieder der AU waren an den AfCFTA-Verhandlungen beteiligt. Davon geh\u00f6ren 47 zu mindestens einer der anerkannten Regionalen Wirtschaftsgemeinschaften (Regional Economic Communities &#8211; RECs), die gem\u00e4\u00df der Pr\u00e4ambel des AfCFTA-Abkommens weiterhin als Bausteine des Handelsabkommens dienen sollen. Folglich waren es die RECs, welche bei den AfCFTA-Verhandlungen f\u00fcr ihre jeweiligen Mitglieder auftraten. Das AfCFTA-Abkommen sieht vor, dass die RECs ihre Rechtsinstrumente, Institutionen und Streitbeilegungsmechanismen beibehalten.<\/p>\n<p>Innerhalb der AU gibt es acht anerkannte regionale Wirtschaftsgemeinschaften, die sich in einigen L\u00e4ndern \u00fcberschneiden und bei denen es sich entweder um pr\u00e4ferenzielle Handelsabkommen (Freihandelsabkommen) oder Zollunionen handelt.<\/p>\n<p>Im Rahmen der AfCFTA haben die RECs verschiedene Aufgaben. Diese sind insbesondere:<\/p>\n<ul>\n<li>Koordinierung der Verhandlungspositionen und Unterst\u00fctzung der Mitgliedsstaaten bei der Umsetzung des Abkommens<\/li>\n<li>L\u00f6sungsorientierte Mediation bei Unstimmigkeiten zwischen den Mitgliedsstaaten<\/li>\n<li>Unterst\u00fctzung der Mitgliedsstaaten bei der Harmonisierung von Z\u00f6llen und anderen Grenzschutzbestimmungen<\/li>\n<li>F\u00f6rderung der Nutzung des AfCFTA-Meldeverfahrens zum Abbau von NTBs<\/li>\n<\/ul>\n<h2><strong>Ausblick auf das AfCFTA<\/strong><\/h2>\n<p>Das AfCFTA hat das Potenzial, die Integration Afrikas in die Weltwirtschaft zu erleichtern und schafft die reale M\u00f6glichkeit einer Neuausrichtung der internationalen Integrations- und Kooperationsmuster.<\/p>\n<p>Ein Handelsabkommen allein ist noch keine Garantie f\u00fcr wirtschaftlichen Erfolg. Damit das Abkommen den prognostizierten Durchbruch erzielt, m\u00fcssen die Mitgliedstaaten den politischen Willen haben, die neuen Regeln konsequent umzusetzen und die daf\u00fcr notwendigen Kapazit\u00e4ten zu schaffen. Insbesondere die kurzfristige Beseitigung von Handelshemmnissen und die Schaffung einer nachhaltigen physischen und digitalen Infrastruktur d\u00fcrften entscheidend sein.<\/p>\n<p>Wenn Sie sich f\u00fcr das AfCFTA interessieren, k\u00f6nnen Sie <a href=\"https:\/\/mideastlaw.de\/de\/nachrichten\/das-african-continental-free-trade-area-afcfta-game-changer-fur-agypten\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>\u00a0eine erweiterte Version dieses Artikels lesen.<\/p>\n<h2><strong>Der Legalmondo African Desk<\/strong><\/h2>\n<p>Mit unseren Experten in <strong>\u00c4gypten, Marokko, Algerien, Tunesien, Libyen, Sudan, Kamerun, C\u00f4te d&#8217;Ivoire, Ghana, Senegal und Malawi <\/strong>unterst\u00fctzen wir Unternehmen bei Investitionen und Gesch\u00e4ftsvorhaben in Afrika<strong>.<\/strong><\/p>\n<p>Ausl\u00e4ndische Unternehmen in afrikanischen L\u00e4ndern, in denen wir nicht direkt mit einem B\u00fcro vertreten sind, k\u00f6nnen wir auch \u00fcber unser Netzwerk von lokalen Partnern unterst\u00fctzen.<\/p>\n<h2><strong>Wie es funktioniert<\/strong><\/h2>\n<ul>\n<li>Wir vereinbaren ein Treffen (pers\u00f6nlich oder online) mit einem unserer Experten, um die Bed\u00fcrfnisse des Mandanten zu verstehen.<\/li>\n<li>Sobald wir die Zusammenarbeit aufgenommen haben, begleiten wir den Mandanten mit einem Rechtsanwalt bei all seinen rechtlichen Angelegenheiten (einzelne F\u00e4lle oder laufende rechtliche Unterst\u00fctzung)<\/li>\n<\/ul>\n<p><strong>Nehmen Sie Kontakt auf, um mehr zu erfahren<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach mehr als 30 Jahren Verhandlungen blickt die Welt nun auf das erste panafrikanische Handelsabkommen, welches 2019 in Kraft getreten ist: Die Afrikanische Kontinentale Freihandelszone (African Continental Free Trade Area &#8211; AfCFTA). Afrika ist mit seinen 55 L\u00e4ndern und rund 1,3 Milliarden Einwohnern nach Asien der zweitgr\u00f6\u00dfte Kontinent der Welt. Das Potenzial des Kontinents ist [&hellip;]<\/p>\n","protected":false},"author":627,"featured_media":21160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10901,10902],"tags":[11046],"class_list":["post-21171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contracts-de","category-distribution-agreements-de","tag-africa-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts\/21171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/users\/627"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/comments?post=21171"}],"version-history":[{"count":5,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts\/21171\/revisions"}],"predecessor-version":[{"id":21286,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts\/21171\/revisions\/21286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media\/21160"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media?parent=21171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/categories?post=21171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/tags?post=21171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}