{"id":20755,"date":"2022-09-05T08:00:00","date_gmt":"2022-09-05T06:00:00","guid":{"rendered":"https:\/\/www.legalmondo.com\/2021\/02\/international-distribution-agreements-7-lessons-history-nike\/"},"modified":"2024-10-16T18:23:33","modified_gmt":"2024-10-16T16:23:33","slug":"internationale-vertriebsvereinbarungen-7-lektionen-geschichte-nike","status":"publish","type":"post","link":"https:\/\/www.legalmondo.com\/de\/2022\/09\/internationale-vertriebsvereinbarungen-7-lektionen-geschichte-nike\/","title":{"rendered":"Internationale Vertriebsvereinbarungen\ufffc | 7 Lektionen aus der Geschichte von Nike\ufffc"},"content":{"rendered":"<h2><strong>Zusammenfassung<\/strong><\/h2>\n<blockquote>\n<p style=\"text-align: justify;\">Anhand der Geschichte von Nike, die sich aus der Biografie des Gr\u00fcnders Phil Knight ableitet, lassen sich einige Lehren \u00a0f\u00fcr internationale Vertriebsvertr\u00e4ge ziehen: Wie man den Vertrag aushandelt, die Vertragsdauer festlegt, die Exklusivit\u00e4t und die Gesch\u00e4ftsziele definiert und die richtige Art der Streitschlichtung bestimmt.<\/p>\n<\/blockquote>\n<h2><strong>Wor\u00fcber ich in diesem Artikel spreche<\/strong><\/h2>\n<ul>\n<li>Der Streit zwischen Blue Ribbon und Onitsuka Tiger und die Geburt von Nike<\/li>\n<li>Wie man eine internationale Vertriebsvereinbarung aushandelt<\/li>\n<li>Vertragliche Exklusivit\u00e4t in einer Handelsvertriebsvereinbarung<\/li>\n<li>Mindestumsatzklauseln in Vertriebsvertr\u00e4gen<\/li>\n<li>Vertragsdauer \u00a0und K\u00fcndigungsfrist<\/li>\n<li>Eigentum an Marken in Handelsvertr\u00e4gen<\/li>\n<li>Die Bedeutung der Mediation bei internationalen Handelsvertr\u00e4gen<\/li>\n<li>Streitbeilegungsklauseln in internationalen Vertr\u00e4gen<\/li>\n<li>Wie wir Ihnen helfen k\u00f6nnen<\/li>\n<\/ul>\n<h2><strong>Der Streit zwischen Blue Ribbon und Onitsuka Tiger und die Geburt von Nike<\/strong><\/h2>\n<p>Warum ist die ber\u00fchmteste Sportbekleidungsmarke der Welt Nike und nicht Onitsuka Tiger?<br \/>\nDie Biographie des Nike-Sch\u00f6pfers Phil Knight mit dem Titel \u201cShoe Dog\u201d gibt hierauf antworten und ist nicht nur f\u00fcr Liebhaber des Genres eine absolut empfehlenswerte Lekt\u00fcre.<\/p>\n<p>Bewegt von seiner Leidenschaft f\u00fcr den Laufsport und seiner Intuition, dass es auf dem amerikanischen Sportschuhmarkt, der damals von Adidas dominiert wurde, eine L\u00fccke gab, importierte Knight 1964 als erster \u00fcberhaupt eine japanische Sportschuhmarke, Onitsuka Tiger, in die USA. \u00a0Mit diesen Sportschuhen konnte sich Knight innerhalb von 6 Jahren einen Marktanteil von satten 70 % sichern.<\/p>\n<p>Das von Knight und seinem ehemaligen College-Trainer Bill Bowerman gegr\u00fcndete Unternehmen hie\u00df damals noch Blue Ribbon Sports.<\/p>\n<p>Die Gesch\u00e4ftsbeziehung zwischen Blue Ribbon-Nike und dem japanischen Hersteller Onitsuka Tiger \u00a0gestaltete sich trotz der sehr guten Verkaufszahlen und den postiven Wachstumsaussichten von \u00a0Beginn an als sehr turbulent.<\/p>\n<p>Als Knight dann kurz nach der Vertragsverl\u00e4ngerung mit dem japanischen Hersteller erfuhr, dass Onitsuka in den USA nach einem anderen Vertriebspartner Ausschau hielt , beschloss Knight \u00a0\u2013 aus Angst, vom Markt ausgeschlossen zu \u00a0werden \u2013 \u00a0sich seinerseits mit einem anderen japanischen Lieferanten zusammenzutun und seine eigene Marke zu gr\u00fcnden. Damit war die sp\u00e4tere Weltmarke Nike geboren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18729 \" src=\"https:\/\/www.legalmondo.com\/wp-content\/uploads\/2021\/02\/SHOES-FOR-FALL-FROM-BRS-e1614288655323.jpg\" alt=\"shoes\" width=\"333\" height=\"432\" \/><\/p>\n<p>Als der <strong>japanische Hersteller Onitsuka <\/strong>von dem Nike-Projekt erfuhr, <strong>verklagte dieser \u00a0Blue Ribbon wegen \u00a0Versto\u00df gegen das Wettbewerbsverbot<\/strong>, \u00a0welches dem Vertriebsh\u00e4ndler die Einfuhr anderer in Japan hergestellter Produkte untersagte, und beendete die Gesch\u00e4ftsbeziehung mit sofortiger Wirkung.<\/p>\n<p><strong>Blue Ribbon f\u00fchrte hiergegen an, dass der Versto\u00df von dem Hersteller Onitsuka Tiger ausging<\/strong>, der \u00a0sich bereits als der Vertrag noch in Kraft war und die Gesch\u00e4fte mehr als gut liefen mit anderen potenziellen Vertriebsh\u00e4ndlern getroffen hatte.<\/p>\n<p>Diese Auseinandersetzung f\u00fchrte zu zwei Gerichtsverfahren, eines in Japan und eines in den USA, die der Geschichte von Nike ein vorzeitiges Ende h\u00e4tten setzen k\u00f6nnen.<\/p>\n<p>Zum Gl\u00fcck (f\u00fcr Nike) entschied der amerikanische Richter zu Gunsten des H\u00e4ndlers und der Streit wurde mit einem Vergleich beendet: Damit begann f\u00fcr Nike die Reise, die sie 15 Jahre sp\u00e4ter zur wichtigsten Sportartikelmarke der Welt machen sollte.<\/p>\n<p>Wir werden sehen, was uns die Geschichte von Nike lehrt und welche Fehler bei einem internationalen Vertriebsvertrag tunlichst vermieden werden sollten.<\/p>\n<h2><strong>Wie verhandelt man eine internationale Handelsvertriebsvereinbarung? <\/strong><\/h2>\n<p>In seiner Biografie schreibt Knight, dass <strong>er bald bedauerte, die Zukunft seines Unternehmens an eine eilig verfasste, wenige Zeilen umfassende Handelsvereinbarung gebunden zu haben, die <\/strong>am Ende einer Sitzung zur Aushandlung der Erneuerung des Vertriebsvertrags geschlossen wurde.<\/p>\n<p>Was beinhaltete diese Vereinbarung?<\/p>\n<p>Die Vereinbarung sah lediglich die Verl\u00e4ngerung des Rechts von Blue Ribbon vor, die Produkte in den USA exklusiv zu vertreiben, und zwar f\u00fcr weitere drei Jahre.<\/p>\n<p>In der Praxis kommt es \u00a0h\u00e4ufig vor, dass sich internationale Vertriebsvertr\u00e4ge auf m\u00fcndliche Vereinbarungen oder sehr einfache Vertragswerke mit kurzer Dauer beschr\u00e4nken. Die \u00fcbliche Erkl\u00e4rung daf\u00fcr ist, dass es auf diese Weise m\u00f6glich ist, die Gesch\u00e4ftsbeziehung zu testen, ohne die vertragliche Bindung zu eng werden zu lassen.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Diese Art, Gesch\u00e4fte zu machen, ist jedoch nicht zu empfehlen \u00a0und kann sogar gef\u00e4hrlich werden: Ein \u00a0Vertrag sollte niemals \u00a0als Last oder Zwang angesehen werden, sondern als Garantie f\u00fcr die Rechte beider Parteien. Einen schriftlichen Vertrag nicht oder nur sehr \u00fcbereilt abzuschlie\u00dfen, bedeutet, grundlegende Elemente der k\u00fcnftigen Beziehung, wie die, die zum Streit zwischen Blue Ribbon und Onitsuka Tiger f\u00fchrten, ohne klare Vereinbarungen zu belassen: Hierzu geh\u00f6ren Aspekte wie <strong>Handelsziele, Investitionen, das Eigentum an Marken<\/strong> \u2013 um nur einige zu benennen.<\/p>\n<\/blockquote>\n<p>Handelt es sich zudem um einen internationalen Vertrag, ist die Notwendigkeit einer vollst\u00e4ndigen und ausgewogenen Vereinbarung noch gr\u00f6\u00dfer, da in Ermangelung von Vereinbarungen zwischen den Parteien oder in Erg\u00e4nzung zu diesen Vereinbarungen ein Recht zur Anwendung kommt, mit dem eine der Parteien nicht vertraut ist, d. h. im Allgemeinen das Recht des Landes, in dem der H\u00e4ndler seinen Sitz hat.<\/p>\n<p>Auch wenn Sie sich nicht in einer Blue-Ribbon-Situation befinden, in der es sich um einen Vertrag handelt, von dem die Existenz des Unternehmens abh\u00e4ngt, sollten internationale Vertr\u00e4ge stets mit Hilfe eines fachkundigen Anwalts besprochen und ausgehandelt werden, der das auf den Vertrag anwendbare Recht kennt und dem Unternehmer helfen kann, die wichtigen Vertragsklauseln zu ermitteln und auszuhandeln.<\/p>\n<h2><strong>Territoriale Exklusivit\u00e4t, kommerzielle Ziele und Mindestumsatzziele <\/strong><\/h2>\n<p>Anlass f\u00fcr den Konflikt zwischen Blue Ribbon und Onitsuka Tiger war zun\u00e4chst einmal die Bewertung der Absatzentwicklung auf dem US-Markt.<\/p>\n<p>Onitsuka argumentierte, dass der Umsatz unter dem Potenzial des US-Marktes liege, w\u00e4hrend nach Angaben von Blue Ribbon die Verkaufsentwicklung sehr positiv sei, da sich der Umsatz bis zu diesem Zeitpunkt jedes Jahr verdoppelt habe und ein bedeutender Anteil des Marktsektors erobert worden sei.<\/p>\n<p>Als Blue Ribbon erfuhr, dass Onituska andere Kandidaten f\u00fcr den Vertrieb seiner Produkte in den USA pr\u00fcfte, und bef\u00fcrchtete, damit bald vom Markt verdr\u00e4ngt zu werden , bereitete Blue Ribbon die Marke Nike als Plan B vor: Als der \u00a0japanische Hersteller diese Marke entdeckte , kam es zu einem Rechtsstreit zwischen den Parteien, der zu einem Eklat f\u00fchrte.<\/p>\n<p>Der Streit h\u00e4tte vielleicht vermieden werden k\u00f6nnen, wenn sich die Parteien auf kommerzielle Ziele geeinigt h\u00e4tten und der Vertrag eine in Alleinvertriebsvereinbarungen \u00fcbliche Klausel enthalten h\u00e4tte, d.h. ein <strong>Mindestabsatzziel f\u00fcr den Vertriebsh\u00e4ndler<\/strong>.<\/p>\n<p>In einer Alleinvertriebsvereinbarung gew\u00e4hrt der Hersteller dem H\u00e4ndler einen <strong>starken Gebietsschutz <\/strong>f\u00fcr die Investitionen, die der H\u00e4ndler zur Erschlie\u00dfung des zugewiesenen Marktes t\u00e4tigt.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Um dieses \u00a0Zugest\u00e4ndnis der Exklusivit\u00e4t auszugleichen, ist es \u00fcblich, dass der Hersteller vom Vertriebsh\u00e4ndler einen so genannten <strong>garantierten Mindestumsatz oder ein Mindestziel <\/strong>verlangt, das der Vertriebsh\u00e4ndler jedes Jahr erreichen muss, um den ihm gew\u00e4hrten privilegierten Status zu behalten.<\/p>\n<\/blockquote>\n<p><strong>F\u00fcr den Fall, dass das Mindestziel nicht erreicht wird<\/strong>, sieht der Vertrag dann in der Regel vor, dass der Hersteller das Recht hat, vom Vertrag zur\u00fcckzutreten (bei einem unbefristeten Vertrag) oder den Vertrag nicht zu verl\u00e4ngern (bei einem befristeten Vertrag) oder aber auch die Gebietsexklusivit\u00e4t aufzuheben bzw. \u00a0einzuschr\u00e4nken.<\/p>\n<p>Der Vertrag zwischen Blue Ribbon und Onitsuka Tiger sah derartige \u00a0Zielvorgaben nicht vor \u2013 und das nachdem er gerade erst um drei Jahre verl\u00e4ngert wurde. Hinzukam, dass sich die Parteien bei der Bewertung der Ergebnisse des Vertriebsh\u00e4ndlers nicht einig waren. Es stellt sich daher die Frage: <strong>Wie k\u00f6nnen in einem Mehrjahresvertrag Mindestumsatzziele vorgesehen werden<\/strong>?<\/p>\n<p>In Ermangelung zuverl\u00e4ssiger Daten verlassen sich die Parteien h\u00e4ufig auf <strong>vorher festgelegte prozentuale Erh\u00f6hungsmechanismen<\/strong>: + 10 % im zweiten Jahr, + 30 % im dritten Jahr, + 50 % im vierten Jahr und so weiter.<\/p>\n<p>Das <strong>Problem bei diesem Automatismus <\/strong>ist, dass dadurch \u00a0Zielvorgaben vereinbart werden, die nicht auf tats\u00e4chlichen Daten \u00fcber die k\u00fcnftige Entwicklung der Produktverk\u00e4ufe, der Verk\u00e4ufe der Wettbewerber und des Marktes im Allgemeinen basieren , und die daher sehr weit von den aktuellen Absatzm\u00f6glichkeiten des H\u00e4ndlers entfernt sein k\u00f6nnen.<\/p>\n<p>So w\u00e4re beispielsweise die Anfechtung des Vertriebsunternehmens wegen Nichterf\u00fcllung der Zielvorgaben f\u00fcr das zweite oder dritte Jahr in einer rezessiven Wirtschaft sicherlich eine fragw\u00fcrdige Entscheidung, die wahrscheinlich zu Meinungsverschiedenheiten f\u00fchren w\u00fcrde.<\/p>\n<p>Besser w\u00e4re eine <strong>Klausel, mit der Ziele von Jahr zu Jahr einvernehmlich festgelegt werden. <\/strong>Diese besagt, dass die Ziele zwischen den Parteien unter Ber\u00fccksichtigung der Umsatzentwicklung in den vorangegangenen Monaten und mit einer gewissen Vorlaufzeit vor Ende des laufenden Jahres vereinbart werden.\u00a0 F\u00fcr den Fall, dass <strong>keine Einigung \u00fcber die neue Zielvorgabe zustande kommt<\/strong>, kann der Vertrag vorsehen, dass die Zielvorgabe des Vorjahres angewandt wird oder dass die Parteien das Recht haben, den Vertrag unter Einhaltung einer bestimmten K\u00fcndigungsfrist zu k\u00fcndigen.<\/p>\n<p>Andererseits <strong>kann die Zielvorgabe auch als Anreiz f\u00fcr den Vertriebsh\u00e4ndler dienen:<\/strong> So kann z. B. vorgesehen werden, dass bei Erreichen eines bestimmten Umsatzes die Vereinbarung erneuert, die Gebietsexklusivit\u00e4t verl\u00e4ngert oder ein bestimmter kommerzieller Ausgleich f\u00fcr das folgende Jahr gew\u00e4hrt wird.<\/p>\n<p>Eine letzte Empfehlung ist die korrekte Handhabung der Mindestzielklausel, sofern sie im Vertrag enthalten ist: Es kommt h\u00e4ufig vor, dass der Hersteller die Erreichung des Ziels f\u00fcr ein bestimmtes Jahr bestreitet, nachdem die Jahresziele \u00fcber einen langen Zeitraum hinweg nicht erreicht oder nicht aktualisiert wurden, ohne dass dies irgendwelche Konsequenzen hatte.<\/p>\n<p>In solchen F\u00e4llen ist es m\u00f6glich, dass der H\u00e4ndler behauptet, dass ein impliziter Verzicht auf diesen vertraglichen Schutz vorliegt und der Widerruf daher nicht g\u00fcltig ist: Um Streitigkeiten zu diesem Thema zu vermeiden, ist es ratsam, in der Mindestzielklausel ausdr\u00fccklich vorzusehen, dass die unterbliebene Anfechtung des Nichterreichens des Ziels w\u00e4hrend eines bestimmten Zeitraums nicht bedeutet, dass auf das Recht, die Klausel in Zukunft zu aktivieren, verzichtet wird.<\/p>\n<h2><strong>Die K\u00fcndigungsfrist f\u00fcr die Beendigung eines internationalen Vertriebsvertrags<\/strong><\/h2>\n<p>Der andere Streitpunkt zwischen den Parteien war die <strong>Verletzung eines Wettbewerbsverbots<\/strong>: Blue Ribbon verkaufte die Marke Nike , obwohl der Vertrag den Verkauf anderer in Japan hergestellter Schuhe untersagte.<\/p>\n<p>Onitsuka Tiger behauptete, Blue Ribbon habe gegen das Wettbewerbsverbot versto\u00dfen, w\u00e4hrend der H\u00e4ndler die Ansicht vertrat , dass er angesichts der bevorstehenden Entscheidung des Herstellers, die Vereinbarung zu k\u00fcndigen, keine andere Wahl hatte.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Diese Art von Streitigkeiten kann vermieden werden, indem f\u00fcr die Beendigung (oder Nichtverl\u00e4ngerung) eine klare K\u00fcndigungsfrist festgelegt wird: Diese Frist hat die grundlegende Funktion, den Parteien die M\u00f6glichkeit zu geben, sich auf die Beendigung der Beziehung vorzubereiten und ihre Aktivit\u00e4ten nach der Beendigung neu zu organisieren.<\/p>\n<\/blockquote>\n<p>Um insbesondere Streitigkeiten wie die zwischen Blue Ribbon und Onitsuka Tiger zu vermeiden, kann in einem internationalen Vertriebsvertrag vorgesehen werden, dass <strong>die Parteien w\u00e4hrend \u00a0der K\u00fcndigungsfristmit anderen potenziellen Vertriebsh\u00e4ndlern und Herstellern in Kontakt treten k\u00f6nnen <\/strong>und dass dies nicht gegen die Ausschlie\u00dflichkeits- und Wettbewerbsverpflichtungen verst\u00f6\u00dft.<\/p>\n<p>Im Fall von Blue Ribbon war der H\u00e4ndler \u00fcber die blo\u00dfe Suche nach einem anderen Lieferanten hinaus sogar noch einen Schritt weiter gegangen, da er begonnen hatte, Nike-Produkte zu verkaufen, w\u00e4hrend der Vertrag mit Onitsuka noch g\u00fcltig war. Dieses Verhalten stellt einen schweren Versto\u00df gegen \u00a0die getroffene Ausschlie\u00dflichkeitsvereinbarung dar.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Ein besonderer Aspekt, der bei der K\u00fcndigungsfrist zu ber\u00fccksichtigen ist, ist die Dauer: Wie lang muss die K\u00fcndigungsfrist sein, um als fair zu gelten? Bei langj\u00e4hrigen Gesch\u00e4ftsbeziehungen ist es wichtig, <strong>der anderen Partei gen\u00fcgend Zeit einzur\u00e4umen, um sich auf dem Markt neu zu positionieren<\/strong>, nach alternativen Vertriebsh\u00e4ndlern oder Lieferanten zu suchen oder (wie im Fall von Blue Ribbon\/Nike) eine eigene Marke zu schaffen und einzuf\u00fchren.<\/p>\n<\/blockquote>\n<p>Ein weiteres Element, das bei der Mitteilung der K\u00fcndigung zu ber\u00fccksichtigen ist, besteht darin, dass die <strong>K\u00fcndigungsfrist so bemessen sein muss, dass der Vertriebsh\u00e4ndler die zur Erf\u00fcllung seiner Verpflichtungen w\u00e4hrend der Vertragslaufzeit get\u00e4tigten Investitionen amortisieren kann<\/strong>; im Fall von Blue Ribbon hatte der Vertriebsh\u00e4ndler auf ausdr\u00fccklichen Wunsch des Herstellers eine Reihe von Einmarkengesch\u00e4ften sowohl an der West- als auch an der Ostk\u00fcste der USA er\u00f6ffnet.<\/p>\n<p>Eine K\u00fcndigung des Vertrags kurz nach seiner Verl\u00e4ngerung und mit einer zu kurzen Vorank\u00fcndigung h\u00e4tte es dem Vertriebsh\u00e4ndler nicht erlaubt, das Vertriebsnetz mit einem Ersatzprodukt neu zu organisieren, was die Schlie\u00dfung der Gesch\u00e4fte, die die japanischen Schuhe bis zu diesem Zeitpunkt verkauft hatten, erzwungen h\u00e4tte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18745 \" src=\"https:\/\/www.legalmondo.com\/wp-content\/uploads\/2021\/02\/sconosciuto.jpg\" alt=\"tiger\" width=\"596\" height=\"445\" \/><\/p>\n<p>Im Allgemeinen ist es ratsam, eine K\u00fcndigungsfrist von <strong>mindestens 6 Monaten <\/strong>vorzusehen. Bei internationalen Vertriebsvertr\u00e4gen sollten jedoch neben den von den Parteien get\u00e4tigten Investitionen auch etwaige <strong>spezifische Bestimmungen des auf den Vertrag anwendbaren Rechts <\/strong>(hier z. B. eine eingehende Analyse der pl\u00f6tzlichen K\u00fcndigung von Vertr\u00e4gen in <a href=\"https:\/\/www.legalmondo.com\/2019\/12\/france-sudden-termination-international-contract\/\" target=\"_blank\" rel=\"noopener\">Frankreich<\/a>) oder <strong>die Rechtsprechung zum Thema R\u00fccktritt von Gesch\u00e4ftsbeziehungen beachtet werden<\/strong> (in einigen F\u00e4llen kann die f\u00fcr einen langfristigen Vertriebskonzessionsvertrag als angemessen erachtete Frist 24 Monate betragen).<\/p>\n<p>Schlie\u00dflich ist es normal, dass der H\u00e4ndler zum Zeitpunkt des Vertragsabschlusses noch im Besitz von <strong>Produktvorr\u00e4ten <\/strong>ist: Dies kann problematisch sein, da der H\u00e4ndler in der Regel die Vorr\u00e4te aufl\u00f6sen m\u00f6chte (Blitzverk\u00e4ufe oder Verk\u00e4ufe \u00fcber Internetkan\u00e4le mit starken Rabatten), was der Gesch\u00e4ftspolitik des Herstellers und der neuen H\u00e4ndler zuwiderlaufen kann.<\/p>\n<p>Um diese Art von Situation zu vermeiden, kann in den Vertriebsvertrag eine Klausel aufgenommen werden, die das Recht des Herstellers auf R\u00fcckkauf der vorhandenen Best\u00e4nde bei Vertragsende regelt, wobei der R\u00fcckkaufpreis bereits festgelegt ist (z. B. in H\u00f6he des Verkaufspreises an den H\u00e4ndler f\u00fcr Produkte der laufenden Saison, mit einem Abschlag von 30 % f\u00fcr Produkte der vorangegangenen Saison und mit einem h\u00f6heren Abschlag f\u00fcr Produkte, die mehr als 24 Monate zuvor verkauft wurden).<\/p>\n<h2><strong>Markeninhaberschaft in einer internationalen Vertriebsvereinbarung <\/strong><\/h2>\n<p>Im Laufe der Vertriebsbeziehung hatte Blue Ribbon eine neuartige Sohle f\u00fcr Laufschuhe entwickelt und die Marken <strong>Cortez und Boston <\/strong>f\u00fcr die Spitzenmodelle der Kollektion gepr\u00e4gt, die beim Publikum sehr erfolgreich waren und gro\u00dfe Popularit\u00e4t erlangten: Bei Vertragsende <strong>beanspruchten nun beide Parteien das Eigentum an den Marken<\/strong>.<\/p>\n<p><strong>Derartige Situationen treten h\u00e4ufig in internationalen Vertriebsbeziehungen auf<\/strong>: Der H\u00e4ndler l\u00e4sst die Marke des Herstellers in dem Land, in dem er t\u00e4tig ist, registrieren, um Konkurrenten daran zu hindern, dies zu tun, und um die Marke im Falle des Verkaufs gef\u00e4lschter Produkte sch\u00fctzen zu k\u00f6nnen; oder es kommt vor, dass der H\u00e4ndler, wie in dem hier behandelten Streitfall, an der Schaffung neuer, f\u00fcr seinen Markt bestimmter Marken mitwirkt.<\/p>\n<p>Am Ende der Gesch\u00e4ftsbeeziehung, wenn keine klare Vereinbarung zwischen den Parteien vorliegt, kann es zu einem Streit wie im Fall Nike kommen: <strong>Wer ist der Eigent\u00fcmer der Marke \u2013 der Hersteller oder der H\u00e4ndler?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18753 \" src=\"https:\/\/www.legalmondo.com\/wp-content\/uploads\/2021\/02\/sconosciuto1.jpg\" alt=\"tiger\" width=\"607\" height=\"406\" srcset=\"https:\/\/www.legalmondo.com\/wp-content\/uploads\/2021\/02\/sconosciuto1.jpg 1100w, https:\/\/www.legalmondo.com\/wp-content\/uploads\/2021\/02\/sconosciuto1-600x401.jpg 600w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/p>\n<p>Um Missverst\u00e4ndnisse zu vermeiden, ist es ratsam, <strong>die Marke in allen L\u00e4ndern zu registrieren, in denen die Produkte vertrieben werden<\/strong>, und nicht nur dort: Im Falle Chinas zum Beispiel ist es ratsam, die Marke auch dann zu registrieren, wenn sie dort nicht vertreiben wird, um zu verhindern, dass Dritte die Marke in b\u00f6ser Absicht \u00fcbernehmen (weitere Informationen <a href=\"https:\/\/www.legalmondo.com\/2020\/02\/china-trade-mark-registration\/\" target=\"_blank\" rel=\"noopener\">finden Sie in diesem Beitrag auf Legalmondo<\/a>).<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Es ist auch ratsam, in den Vertriebsvertrag <strong>eine Klausel <\/strong>aufzunehmen<strong>, die dem H\u00e4ndler die Eintragung der Marke <\/strong>(oder \u00e4hnlicher Marken) in dem Land, in dem er t\u00e4tig ist, <strong>untersagt <\/strong>und dem Hersteller ausdr\u00fccklich das Recht einr\u00e4umt, die \u00dcbertragung der Marke zu verlangen, falls dies dennoch geschieht.<\/p>\n<\/blockquote>\n<p>Eine solche Klausel h\u00e4tte die Entstehung des Rechtsstreits zwischen Blue Ribbon und Onitsuka Tiger verhindert.<\/p>\n<p>Der von uns geschilderte Sachverhalt stammt aus dem <strong>Jahr 1976<\/strong>: Heutzutage ist es ratsam, im Vertrag nicht nur die Eigentumsverh\u00e4ltnisse an der Marke und die Art und Weise der Nutzung durch den H\u00e4ndler und sein Vertriebsnetz zu kl\u00e4ren, sondern auch die <strong>Nutzung der Marke wie auch der Unterscheidungszeichen des Herstellers in den Kommunikationskan\u00e4len, insbesondere in den sozialen Medien, <\/strong>zu regeln.<\/p>\n<p>Es ist ratsam, eindeutig festzulegen, dass niemand anderes als der Hersteller Eigent\u00fcmer der Social-Media-Profile wie auch der erstellten Inhalte und der Daten ist, die durch die Verkaufs-, Marketing- und Kommunikationsaktivit\u00e4ten in dem Land, in dem der H\u00e4ndler t\u00e4tig ist, generiert werden, und dass er nur die Lizenz hat, diese gem\u00e4\u00df den Anweisungen des Eigent\u00fcmers zu nutzen.<\/p>\n<p>Dar\u00fcber hinaus ist es sinnvoll, in der Vereinbarung festzulegen, wie die Marke verwendet wird und welche Kommunikations- und Verkaufsf\u00f6rderungsma\u00dfnahmen auf dem Markt ergriffen werden, um Initiativen zu vermeiden, die negative oder kontraproduktive Auswirkungen haben k\u00f6nnten.<\/p>\n<p>Die Klausel kann auch durch die Festlegung von <strong>Vertragsstrafen <\/strong>f\u00fcr den Fall verst\u00e4rkt werden, dass sich der H\u00e4ndler bei Vertragsende weigert, die Kontrolle \u00fcber die digitalen Kan\u00e4le und die im Rahmen der Gesch\u00e4ftst\u00e4tigkeit erzeugten Daten zu \u00fcbertragen.<\/p>\n<h2><strong>Mediation in internationalen Handelsvertr\u00e4gen <\/strong><\/h2>\n<p>Ein weiterer interessanter Punkt, der sich am \u00a0Fall Blue Ribbon vs. Onitsuka Tiger erl\u00e4utern l\u00e4sst , steht im Zusammenhang mit der <strong>Bew\u00e4ltigung von Konflikten in internationalen Vertriebsbeziehungen<\/strong>: Situationen wie die, die wir gesehen haben, k\u00f6nnen durch den Einsatz von Mediation effektiv gel\u00f6st werden.<\/p>\n<p>Dabei handelt es sich um einen Schlichtungsversuch, mit dem ein spezialisiertes Gremium oder ein Mediator betraut wird, um eine g\u00fctliche Einigung zu erzielen und ein Gerichtsverfahren zu vermeiden.<\/p>\n<p>Die Mediation kann im Vertrag als <strong>erster Schritt <\/strong>vor einem eventuellen Gerichts- oder Schiedsverfahren vorgesehen sein oder sie kann freiwillig im Rahmen eines bereits laufenden Gerichts- oder Schiedsverfahrens eingeleitet werden.<\/p>\n<p><strong>Die Vorteile sind vielf\u00e4ltig<\/strong>: Der wichtigste ist die M\u00f6glichkeit, <strong>eine wirtschaftliche \u00a0L\u00f6sung zu <\/strong>finden<strong>, die die Fortsetzung der Beziehung erm\u00f6glicht<\/strong>, anstatt nur nach Wegen zur Beendigung der Gesch\u00e4ftsbeziehung zwischen den Parteien zu suchen.<\/p>\n<p>Ein weiterer interessanter Aspekt der Mediation ist die <strong>\u00dcberwindung von pers\u00f6nlichen Konflikten<\/strong>: Im Fall Blue Ribbon vs. Onitsuka zum Beispiel war ein entscheidendes Element f\u00fcr die Eskalation der Probleme zwischen den Parteien die schwierige pers\u00f6nliche Beziehung zwischen dem CEO von Blue Ribbon und dem Exportmanager des japanischen Herstellers, die durch starke kulturelle Unterschiede versch\u00e4rft wurde.<\/p>\n<p>Der Mediationsprozess f\u00fchrt eine dritte Person ein, die <strong>in der Lage ist, einen Dialog mit den Parteien zu f\u00fchren und sie bei der Suche nach L\u00f6sungen von gegenseitigem Interesse zu unterst\u00fctzen<\/strong>, was entscheidend sein kann, um Kommunikationsprobleme oder pers\u00f6nliche Feindseligkeiten zu \u00fcberwinden.<\/p>\n<p>F\u00fcr alle, die sich f\u00fcr dieses Thema interessieren, verweisen wir auf <a href=\"https:\/\/www.legalmondo.com\/2020\/07\/importance-mediation-distribution-contracts\/\" target=\"_blank\" rel=\"noopener\">den hierzu verfassten \u00a0Beitrag auf Legalmondo<\/a> sowie \u00a0auf die Aufzeichnung eines k\u00fcrzlich durchgef\u00fchrten Webinars zur <a href=\"https:\/\/www.youtube.com\/watch?v=NISq4NqJWhw\" target=\"_blank\" rel=\"noopener\">Mediation internationaler Konflikte<\/a>.<\/p>\n<h2><strong>Streitbeilegungsklauseln in internationalen Vertriebsvereinbarungen <\/strong><\/h2>\n<p>Der Streit zwischen Blue Ribbon und Onitsuka Tiger f\u00fchrte dazu, dass die Parteien zwei parallele Gerichtsverfahren einleiteten, eines in den USA (durch den \u00a0H\u00e4ndler) und eines in Japan (durch den \u00a0Hersteller).<\/p>\n<p>Dies war nur deshalb\u00a0 m\u00f6glich, weil der Vertrag <strong>nicht ausdr\u00fccklich vorsah, wie etwaige k\u00fcnftige Streitigkeiten beigelegt werden sollten<\/strong>.\u00a0 In der Konsequenz f\u00fchrte dies zu einer prozessual sehr komplizierten Situation mit gleich zwei gerichtlichen Fronten in verschiedenen L\u00e4ndern.<\/p>\n<p>Die Klauseln, die festlegen, welches Recht auf einen Vertrag anwendbar ist und wie Streitigkeiten beigelegt werden, werden in der Praxis als &#8222;<em>Mitternachtsklauseln<\/em>&#8220; bezeichnet, da sie oft die letzten Klauseln im Vertrag sind, die sp\u00e4t in der Nacht ausgehandelt werden.<\/p>\n<p>Es handelt sich hierbei \u00a0um sehr wichtige Klauseln, die bewusst gew\u00e4hlt\u00a0 werden m\u00fcssen, um unwirksame oder kontraproduktive L\u00f6sungen zu vermeiden.<\/p>\n<h2><strong>Wie wir Ihnen helfen k\u00f6nnen <\/strong><\/h2>\n<p>Der Abschluss eines internationalen Handelsvertriebsvertrags ist eine wichtige Investition, denn er regelt die vertragliche Beziehungen zwischen den Parteien verbindlich f\u00fcr die Zukunft\u00a0 und gibt ihnen die Instrumente an die Hand, um alle Situationen zu bew\u00e4ltigen, die sich aus der k\u00fcnftigen Zusammenarbeit ergeben werden.<\/p>\n<p>Es ist nicht nur wichtig, eine korrekte, vollst\u00e4ndige und ausgewogene Vereinbarung auszuhandeln und abzuschlie\u00dfen, sondern auch zu wissen, wie sie im Laufe der Jahre zu handhaben ist, vor allem, wenn Konfliktsituationen auftreten.<\/p>\n<p>Legalmondo bietet Ihnen die M\u00f6glichkeit, mit Anw\u00e4lten zusammenzuarbeiten, die in mehr als 60 L\u00e4ndern Erfahrung im internationalen Handelsvertrieb haben: \u00a0Bei bestehendem Beratungsbedarf schreiben Sie uns.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zusammenfassung Anhand der Geschichte von Nike, die sich aus der Biografie des Gr\u00fcnders Phil Knight ableitet, lassen sich einige Lehren \u00a0f\u00fcr internationale Vertriebsvertr\u00e4ge ziehen: Wie man den Vertrag aushandelt, die Vertragsdauer festlegt, die Exklusivit\u00e4t und die Gesch\u00e4ftsziele definiert und die richtige Art der Streitschlichtung bestimmt. Wor\u00fcber ich in diesem Artikel spreche Der Streit zwischen Blue [&hellip;]<\/p>\n","protected":false},"author":43,"featured_media":34290,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10903,10906,10901,10902],"tags":[10907],"class_list":["post-20755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intellectual-property-de","category-trademark-and-patents-de","category-contracts-de","category-distribution-agreements-de","tag-italy-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts\/20755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/comments?post=20755"}],"version-history":[{"count":3,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts\/20755\/revisions"}],"predecessor-version":[{"id":30606,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/posts\/20755\/revisions\/30606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media\/34290"}],"wp:attachment":[{"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/media?parent=20755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/categories?post=20755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalmondo.com\/de\/wp-json\/wp\/v2\/tags?post=20755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}